{"id":42,"count":1,"description":"","link":"https:\/\/sublimerevenue.com\/blog\/tag\/giving","name":"giving","slug":"giving","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>giving Archives - Sublime Revenue&#039;s Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sublimerevenue.com\/blog\/tag\/giving\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"giving Archives - Sublime Revenue&#039;s Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sublimerevenue.com\/blog\/tag\/giving\" \/>\n<meta property=\"og:site_name\" content=\"Sublime Revenue&#039;s Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#organization\",\"name\":\"Sublime Revenue\",\"url\":\"https:\/\/sublimerevenue.com\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/sublimerevenue.com\/blog\/wp-content\/uploads\/2018\/10\/logo_big.png\",\"contentUrl\":\"https:\/\/sublimerevenue.com\/blog\/wp-content\/uploads\/2018\/10\/logo_big.png\",\"width\":735,\"height\":86,\"caption\":\"Sublime Revenue\"},\"image\":{\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#website\",\"url\":\"https:\/\/sublimerevenue.com\/blog\/\",\"name\":\"Sublime Revenue&#039;s Blog\",\"description\":\"Commission Per Any Action\",\"publisher\":{\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sublimerevenue.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sublimerevenue.com\/blog\/tag\/giving#webpage\",\"url\":\"https:\/\/sublimerevenue.com\/blog\/tag\/giving\",\"name\":\"giving Archives - Sublime Revenue&#039;s Blog\",\"isPartOf\":{\"@id\":\"https:\/\/sublimerevenue.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sublimerevenue.com\/blog\/tag\/giving#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sublimerevenue.com\/blog\/tag\/giving\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sublimerevenue.com\/blog\/tag\/giving#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sublimerevenue.com\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"giving\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"giving Archives - Sublime Revenue&#039;s Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sublimerevenue.com\/blog\/tag\/giving","og_locale":"en_US","og_type":"article","og_title":"giving Archives - Sublime Revenue&#039;s Blog","og_url":"https:\/\/sublimerevenue.com\/blog\/tag\/giving","og_site_name":"Sublime Revenue&#039;s Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/sublimerevenue.com\/blog\/#organization","name":"Sublime Revenue","url":"https:\/\/sublimerevenue.com\/blog\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/sublimerevenue.com\/blog\/#logo","inLanguage":"en-US","url":"https:\/\/sublimerevenue.com\/blog\/wp-content\/uploads\/2018\/10\/logo_big.png","contentUrl":"https:\/\/sublimerevenue.com\/blog\/wp-content\/uploads\/2018\/10\/logo_big.png","width":735,"height":86,"caption":"Sublime Revenue"},"image":{"@id":"https:\/\/sublimerevenue.com\/blog\/#logo"}},{"@type":"WebSite","@id":"https:\/\/sublimerevenue.com\/blog\/#website","url":"https:\/\/sublimerevenue.com\/blog\/","name":"Sublime Revenue&#039;s Blog","description":"Commission Per Any Action","publisher":{"@id":"https:\/\/sublimerevenue.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sublimerevenue.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/sublimerevenue.com\/blog\/tag\/giving#webpage","url":"https:\/\/sublimerevenue.com\/blog\/tag\/giving","name":"giving Archives - Sublime Revenue&#039;s Blog","isPartOf":{"@id":"https:\/\/sublimerevenue.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/sublimerevenue.com\/blog\/tag\/giving#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sublimerevenue.com\/blog\/tag\/giving"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sublimerevenue.com\/blog\/tag\/giving#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sublimerevenue.com\/blog"},{"@type":"ListItem","position":2,"name":"giving"}]}]}},"_links":{"self":[{"href":"https:\/\/sublimerevenue.com\/blog\/wp-json\/wp\/v2\/tags\/42"}],"collection":[{"href":"https:\/\/sublimerevenue.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sublimerevenue.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sublimerevenue.com\/blog\/wp-json\/wp\/v2\/posts?tags=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}